{"id":58182,"date":"2025-03-31T20:19:34","date_gmt":"2025-03-31T18:19:34","guid":{"rendered":"https:\/\/www.bgamstetten.ac.at\/?p=58182"},"modified":"2025-04-03T11:35:02","modified_gmt":"2025-04-03T09:35:02","slug":"schulschwimmcup-2025","status":"publish","type":"post","link":"https:\/\/www.bgamstetten.ac.at\/index.php\/2025\/03\/31\/schulschwimmcup-2025\/","title":{"rendered":"Schulschwimmcup 2025"},"content":{"rendered":"<style type=\"text\/css\"><\/style>\n<p>Nach einer f\u00fcnfj\u00e4hrigen Pause wurden heuer am 31.M\u00e4rz im Hallenbad Amstetten wieder die Bezirksmeisterschaften im Schwimmen und Rettungsschwimmen vom \u00d6sterreichischen Jugendrotkreuz durchgef\u00fchrt. Mit einer Rekordbeteiligung von \u00fcber 70 motivierten Schwimmerinnen und Schwimmern, begleitet von vier Lehrkr\u00e4ften, waren wir in allen Altersstufen und Bewerben am Start.<\/p>\n\n\n\n<p>Dieser Wettkampf wurde als Teambewerb durchgef\u00fchrt. Neben der 8x50m Staffel im freien Stil f\u00fcr die Altersstufe D (1. und 2. Klasse) gab es einen Kombinationsbewerb, bei dem die Zeitsumme von 8x50m Staffel und Rettungsschwimmen gebildet wurde. Unsere Sch\u00fclerinnen und Sch\u00fcler traten sowohl in den Kategorien weiblich und m\u00e4nnlich, als auch im Mixedbewerb an. Nach hervorragenden Leistungen \u00fcber 50m mussten sich unsere Teilnehmerinnen und Teilnehmer noch im Rettungsschwimmen (Kleiderschwimmen, R\u00fcckenschwimmen mit Basketball, Ziehen und Luftmatratzenschwimmen) beweisen. Die ausgezeichneten Leistungen aller f\u00fchrten zu einem tollen Gesamterfolg unserer Schule. Wir sind sehr stolz und gratulieren sechs der gestarteten Teams zum hervorragenden 1. Platz: M\u00e4dchen 1.\/2. Klasse, Burschen 1.\/2. Klasse, M\u00e4dchen 3.\/4. Klasse, Burschen 3.\/4. Klasse, M\u00e4dchen Oberstufe und Burschen Oberstufe. Auch unsere mixed Teams (3 M\u00e4dchen und 3 Burschen) haben sich tapfer geschlagen und einen 2. bzw. 3. Platz erk\u00e4mpft.&nbsp;<\/p>\n\n\n\n<p>Hoffentlich findet der Schwimmcup in Amstetten n\u00e4chstes Jahr wieder eine Fortsetzung. Wir werden jedenfalls im Schwimmunterricht flei\u00dfig weitertrainieren und uns darauf freuen.\u00a0<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Tanja Leichtfried, BEd und Mag. Sylvia Spring<\/em><\/p>\n\n\n<div class=\"sgdg-gallery-container\" data-sgdg-hash=\"7f121b1c5e41907e0bc682559e3b974e2b0b3763379420d695bcb579855e7f85\"><div class=\"sgdg-loading\"><div><\/div><\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach einer f\u00fcnfj\u00e4hrigen Pause wurden heuer am 31.M\u00e4rz im Hallenbad Amstetten wieder die Bezirksmeisterschaften im Schwimmen und Rettungsschwimmen vom \u00d6sterreichischen Jugendrotkreuz durchgef\u00fchrt. Mit einer Rekordbeteiligung von \u00fcber 70 motivierten Schwimmerinnen und Schwimmern, begleitet von vier Lehrkr\u00e4ften, waren wir in allen Altersstufen und Bewerben am Start. Dieser Wettkampf wurde als Teambewerb durchgef\u00fchrt. Neben der 8x50m Staffel&#8230;<\/p>\n","protected":false},"author":13,"featured_media":58183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,13,4],"tags":[44],"class_list":["post-58182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-119","category-aktuelles","category-sportliches","tag-sport"],"_links":{"self":[{"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/58182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/comments?post=58182"}],"version-history":[{"count":1,"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/58182\/revisions"}],"predecessor-version":[{"id":58184,"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/58182\/revisions\/58184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/media\/58183"}],"wp:attachment":[{"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/media?parent=58182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/categories?post=58182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bgamstetten.ac.at\/index.php\/wp-json\/wp\/v2\/tags?post=58182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}